{"id":1098,"date":"2024-08-21T08:37:41","date_gmt":"2024-08-21T08:37:41","guid":{"rendered":"https:\/\/www.golfstore.no\/butikk\/sola\/?page_id=1098"},"modified":"2026-06-30T12:17:54","modified_gmt":"2026-06-30T12:17:54","slug":"demodager","status":"publish","type":"page","link":"https:\/\/www.golfstore.no\/butikk\/sola\/demodager\/","title":{"rendered":"Demodager 2026"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_crosspost_to_16":false,"_crosspost_to_17":false,"_crosspost_to_18":false,"_crosspost_to_19":false,"_crosspost_to_20":false,"_crosspost_to_21":false,"_crosspost_to_22":false,"_crosspost_to_23":false,"_crosspost_to_24":false,"_crosspost_to_25":false,"_crosspost_to_26":false,"_crosspost_to_27":false,"_crosspost_to_28":false,"_crosspost_to_30":false,"_crosspost_to_31":false,"_crosspost_to_32":false,"_crosspost_to_33":false,"_crosspost_to_34":false,"_crosspost_to_36":false,"_crosspost_to_37":false,"_crosspost_to_40":false,"_crosspost_to_41":false,"_crosspost_to_43":false,"_crosspost_to_45":false,"_crosspost_to_46":false,"_crosspost_to_47":false,"_crosspost_to_48":false,"_crosspost_to_50":false,"_crosspost_to_51":false,"_crosspost_to_54":false,"_crosspost_to_55":false,"_crosspost_to_56":false,"_crosspost_to_58":false,"_crosspost_to_60":false,"_crosspost_to_61":false,"_crosspost_to_62":false,"_crosspost_to_63":false,"_crosspost_to_64":false,"_crosspost_to_67":false,"_crosspost_to_68":false,"_crosspost_to_69":false,"_crosspost_to_70":false,"_crosspost_to_72":false,"_crosspost_to_73":false,"_crosspost_to_74":false,"_crosspost_to_75":false,"_crosspost_to_77":false,"_crosspost_to_78":false,"_crosspost_to_79":false,"_crosspost_to_80":false,"_crosspost_to_81":false,"_crosspost_to_82":false,"_crosspost_to_83":false,"_crosspost_to_84":false,"_crosspost_to_85":false,"_crosspost_to_86":false,"_crosspost_to_87":false,"_crosspost_to_88":false,"_crosspost_to_89":false,"_crosspost_to_90":false,"_crosspost_to_91":false,"_crosspost_to_92":false,"_crosspost_to_93":false,"_crosspost_to_94":false,"_crosspost_to_95":false,"_crosspost_to_96":false,"_crosspost_to_97":false,"_crosspost_to_98":false,"_crosspost_to_99":false,"_crosspost_to_101":false,"_crosspost_to_102":false,"_crosspost_to_104":false,"_crosspost_to_105":false,"_crosspost_to_107":false,"_crosspost_to_109":false,"_crosspost_to_110":false,"_crosspost_to_111":false,"_crosspost_to_112":false,"_crosspost_to_114":false,"_crosspost_to_115":false,"_crosspost_to_116":false,"_crosspost_to_117":false,"_crosspost_to_118":false,"_crosspost_to_119":false,"_crosspost_to_120":false,"_crosspost_to_121":false,"_crosspost_to_122":false,"_crosspost_to_123":false,"_crosspost_to_129":false,"_crosspost_to_130":false,"_crosspost_to_131":false,"_crosspost_to_132":false,"_crosspost_to_134":false,"_crosspost_to_136":false,"_crosspost_to_137":false,"_crosspost_to_140":false,"_crosspost_to_141":false,"_crosspost_to_142":false,"_crosspost_to_143":false,"_crosspost_to_144":false,"_crosspost_to_145":false,"_crosspost_to_146":false,"_crosspost_to_147":false,"_crosspost_to_148":false,"_crosspost_to_149":false,"_crosspost_to_150":false,"_crosspost_to_151":false,"_crosspost_to_152":false,"_crosspost_to_153":false,"_crosspost_to_156":false,"_crosspost_to_157":false,"_crosspost_to_158":false,"_crosspost_to_159":false,"_crosspost_to_160":false,"_crosspost_to_161":false,"_crosspost_to_162":false,"_crosspost_to_163":false,"_crosspost_to_164":false,"_crosspost_to_165":false,"_crosspost_to_167":false,"_crosspost_to_168":false,"_crosspost_to_169":false,"_crosspost_to_170":false,"_crosspost_to_171":false,"_crosspost_to_174":false,"_crosspost_to_175":false,"_crosspost_to_176":false,"_crosspost_to_178":false,"_crosspost_to_179":false,"_crosspost_to_180":false,"_crosspost_to_183":false,"_crosspost_to_185":false,"_crosspost_to_186":false,"_crosspost_to_187":false,"_crosspost_to_188":false,"_crosspost_to_189":false,"_crosspost_to_193":false,"_crosspost_to_194":false,"_crosspost_to_196":false,"_crosspost_to_197":false,"_crosspost_to_199":false,"_crosspost_to_200":false,"_crosspost_to_204":false,"_crosspost_to_206":false,"_crosspost_to_207":false,"_crosspost_to_208":false,"_crosspost_to_209":false,"_crosspost_to_210":false,"_crosspost_to_211":false,"_crosspost_to_212":false,"_crosspost_to_213":false,"_crosspost_to_216":false,"_crosspost_to_218":false,"_crosspost_to_219":false,"_crosspost_to_220":false,"_crosspost_to_221":false,"_crosspost_to_224":false,"_crosspost_to_225":false,"_crosspost_to_226":false,"_crosspost_to_227":false,"_crosspost_to_229":false,"_crosspost_to_230":false,"_crosspost_to_231":false,"_crosspost_to_232":false,"_crosspost_to_233":false,"_crosspost_to_234":false,"_crosspost_to_235":false,"_crosspost_to_236":false,"_crosspost_to_237":false,"_crosspost_to_239":false,"_crosspost_to_240":false,"_crosspost_to_241":false,"_crosspost_to_242":false,"_crosspost_to_243":false,"_crosspost_to_244":false,"_crosspost_to_245":false,"_crosspost_to_246":false,"_crosspost_to_247":false,"_crosspost_to_251":false,"_crosspost_to_253":false,"_crosspost_to_254":false,"_crosspost_to_255":false,"_crosspost_to_256":false,"_crosspost_to_257":false,"_crosspost_to_259":false,"_crosspost_to_260":false,"_crosspost_to_261":false,"_crosspost_to_262":false,"_crosspost_to_263":false,"_crosspost_to_264":false,"_crosspost_to_266":false,"_crosspost_to_267":false,"_crosspost_to_268":false,"_crosspost_to_269":false,"_crosspost_to_271":false,"_crosspost_to_272":false,"_crosspost_to_273":false,"_crosspost_to_274":false,"_crosspost_to_275":false,"_crosspost_to_277":false,"_crosspost_to_278":false,"_crosspost_to_279":false,"_crosspost_to_281":false,"_crosspost_to_282":false,"_crosspost_to_283":false,"_crosspost_to_285":false,"_crosspost_to_286":false,"_crosspost_to_287":false,"_crosspost_to_288":false,"_crosspost_to_289":false,"_crosspost_to_290":false},"class_list":["post-1098","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Demodager 2026 - Sola GK<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.golfstore.no\/butikk\/sola\/demodager\/\" \/>\n<meta property=\"og:locale\" content=\"nb_NO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Demodager 2026 - Sola GK\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.golfstore.no\/butikk\/sola\/demodager\/\" \/>\n<meta property=\"og:site_name\" content=\"Sola GK\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-30T12:17:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.golfstore.no/butikk\\\/sola\\\/demodager\\\/\",\"url\":\"https:\\\/\\\/www.golfstore.no/butikk\\\/sola\\\/demodager\\\/\",\"name\":\"Demodager 2026 - Sola GK\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.golfstore.no/butikk\\\/sola\\\/#website\"},\"datePublished\":\"2024-08-21T08:37:41+00:00\",\"dateModified\":\"2026-06-30T12:17:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.golfstore.no/butikk\\\/sola\\\/demodager\\\/#breadcrumb\"},\"inLanguage\":\"nb-NO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.golfstore.no/butikk\\\/sola\\\/demodager\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.golfstore.no/butikk\\\/sola\\\/demodager\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.golfstore.no/butikk\\\/sola\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Demodager 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.golfstore.no/butikk\\\/sola\\\/#website\",\"url\":\"https:\\\/\\\/www.golfstore.no/butikk\\\/sola\\\/\",\"name\":\"Sola GK\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.golfstore.no/butikk\\\/sola\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nb-NO\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Demodager 2026 - Sola GK","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.golfstore.no\/butikk\/sola\/demodager\/","og_locale":"nb_NO","og_type":"article","og_title":"Demodager 2026 - Sola GK","og_url":"https:\/\/www.golfstore.no\/butikk\/sola\/demodager\/","og_site_name":"Sola GK","article_modified_time":"2026-06-30T12:17:54+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.golfstore.no\/butikk\/sola\/demodager\/","url":"https:\/\/www.golfstore.no\/butikk\/sola\/demodager\/","name":"Demodager 2026 - Sola GK","isPartOf":{"@id":"https:\/\/www.golfstore.no\/butikk\/sola\/#website"},"datePublished":"2024-08-21T08:37:41+00:00","dateModified":"2026-06-30T12:17:54+00:00","breadcrumb":{"@id":"https:\/\/www.golfstore.no\/butikk\/sola\/demodager\/#breadcrumb"},"inLanguage":"nb-NO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.golfstore.no\/butikk\/sola\/demodager\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.golfstore.no\/butikk\/sola\/demodager\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.golfstore.no\/butikk\/sola\/"},{"@type":"ListItem","position":2,"name":"Demodager 2026"}]},{"@type":"WebSite","@id":"https:\/\/www.golfstore.no\/butikk\/sola\/#website","url":"https:\/\/www.golfstore.no\/butikk\/sola\/","name":"Sola GK","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.golfstore.no\/butikk\/sola\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nb-NO"}]}},"_links":{"self":[{"href":"https:\/\/www.golfstore.no\/butikk\/sola\/wp-json\/wp\/v2\/pages\/1098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.golfstore.no\/butikk\/sola\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.golfstore.no\/butikk\/sola\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.golfstore.no\/butikk\/sola\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.golfstore.no\/butikk\/sola\/wp-json\/wp\/v2\/comments?post=1098"}],"version-history":[{"count":34,"href":"https:\/\/www.golfstore.no\/butikk\/sola\/wp-json\/wp\/v2\/pages\/1098\/revisions"}],"predecessor-version":[{"id":1513,"href":"https:\/\/www.golfstore.no\/butikk\/sola\/wp-json\/wp\/v2\/pages\/1098\/revisions\/1513"}],"wp:attachment":[{"href":"https:\/\/www.golfstore.no\/butikk\/sola\/wp-json\/wp\/v2\/media?parent=1098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}